{"id":6071,"date":"2022-09-29T15:35:23","date_gmt":"2022-09-29T13:35:23","guid":{"rendered":"https:\/\/www.diversia360.com\/enit\/?p=6071"},"modified":"2024-03-22T14:35:52","modified_gmt":"2024-03-22T13:35:52","slug":"el-para-que-de-enit","status":"publish","type":"post","link":"https:\/\/www.diversia360.com\/enit\/el-para-que-de-enit\/","title":{"rendered":"EL PARA QU\u00c9 DE ENIT"},"content":{"rendered":"<p class=\"reader-text-block__paragraph\">La semana pasada te hablaba sobre el emprendimiento, algo que, aunque no es camino f\u00e1cil, algunos \u201capasionados\u201d lo llevamos en nuestro ADN y luchamos por \u00e9l contra viento y marea.<\/p>\n<p class=\"reader-text-block__paragraph\">Hace unos d\u00edas, cenando con un grupo de amigos, uno de ellos me pregunt\u00f3 \u201cImma, \u00bfpor qu\u00e9 decidiste embarcarte en ENIT cuando t\u00fa ya formabas parte de varios comit\u00e9s de direcci\u00f3n en\u00a0empresas muy potentes, y formabas parte del equipo de Acad\u00e9micos en\u00a0EAE desde casi una d\u00e9cada? \u00bfQu\u00e9 te movi\u00f3 a meterte en todo este torbellino del emprendimiento?\u201d y lo mejor del caso es que mis ojos empezaron a brillar, por emociones enfrentadas entre el entusiasmo por abrir puertas, el esfuerzo del logro siguiendo un objetivo amplio, la alegr\u00eda del compartir junto a la angustia ante la incertidumbre y los problemas que van sucediendo en el proceso\u2026 Pero las palabras salieron solas: \u201cporque sent\u00ed la necesidad de aportar mis conocimientos y mi experiencia a todos aquellos que realmente desean resolver sus problemas y clarificar sus dudas cuando lo necesitan, al sentirse desorientados, sin motivaci\u00f3n, con miedos, con falta de decisi\u00f3n, y que quieren realmente superarse, porque saben que necesitan un\u00a0cambio en sus vidas, para encontrar salidas mucho m\u00e1s productivas personal y profesionalmente, pero no saben ni por donde empezar. Yo he pasado el mismo proceso que ellos, y s\u00e9 c\u00f3mo afrontarlo, por eso quiero ahorrarles tiempo y dinero, y sobre todo, muchos dolores de cabeza en el camino. Cuando impart\u00eda clases en Escuela de Negocios, me di cuenta de que algunos alumnos estaban cursando un Master, porque era \u201clo que tocaba\u201d para seguir su formaci\u00f3n universitaria, porque as\u00ed se lo hab\u00edan recomendado y sus padres lo \u201cesponsorizaban\u201d, as\u00ed alargaban el enfrentarse al mercado laboral hasta que llegase la oportunidad, y puede ser una salida temporal, pero realmente eso no es lo que necesitaban, incluso cursan uno que no es coherente en ocasiones con su carrera profesional, pero se sobrevalora el conocimiento y se piensa: para algo servir\u00e1. Frecuentemente esas personas simplemente lo que necesitan es a alguien que les tienda una mano y les facilite ordenar sus ideas, sus anhelos, conocerse mejor, o que les ayude a abrir los ojos y decidir qu\u00e9 formaci\u00f3n superior es la que realmente va a llevarles a alcanzar sus verdaderos objetivos, coherentemente tanto a nivel personal como profesional, (y d\u00f3nde pueden encontrar ese tipo de formaci\u00f3n). Por eso decid\u00ed salir de mi zona de confort y poner toda la carne en el asador, explicaros desde la experiencia, desde la realidad del mercado laboral, desde la visi\u00f3n de quien recluta en la Direcci\u00f3n de\u00a0RRHH y como Head Hunter, y desde una perspectiva acad\u00e9mica como profesora formando a m\u00e1s de 5.000 alumnos de m\u00e1s de 57 masters diferentes, que mostraban la gran mayor\u00eda los mismos problemas y dudas a la hora de afrontar su candidatura posicion\u00e1ndose con \u00e9xito en el mercado laboral\u201d.<\/p>\n<div class=\"reader-image-block reader-image-block--full-width\">\n<figure class=\"reader-image-block__figure\">\n<div class=\"ivm-image-view-model   \">\n<div class=\"ivm-view-attr__img-wrapper ivm-view-attr__img-wrapper--use-img-tag display-flex\n\n    \"><a href=\"https:\/\/www.diversia360.com\/enit\/contacto\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<p class=\"reader-text-block__paragraph\">ENIT es la primera Escuela de Negocios nacida de la realidad de las personas. Lamento decirlo, pero veo a muchos gur\u00fas en las redes que \u00a0hablan muy bien y prometen m\u00e1s a\u00fan, pero que realmente te est\u00e1n vendiendo humo, tratando algo tan complejo con simple p\u00edldoras expr\u00e9s. Por esto he creado ENIT, y est\u00e1 pensada por y para las personas, desde un trabajo completo, directo y pr\u00e1ctico, muy real, contemplando el punto de partida y las necesidades que cada uno tenemos, y no puedes dar \u201ccaf\u00e9 para todos\u201d y mucho menos \u201cexpr\u00e9s\u201d. De ah\u00ed que ENIT cuente con diferentes programas (Mentoring 1to1, Lidera-T 360\u00ae, Impulsa-T 360\u00ae y Orienta-T 360\u00ae).<\/p>\n<p class=\"reader-text-block__paragraph\">Mediante nuestra metodolog\u00eda\u00a0\u00fanica podr\u00e1s formar parte\u00a0de una comunidad de profesionales comprometidos\u00a0y conocer todas las herramientas necesarias para convertir tus capacidades en decisiones de \u00e9xito.<\/p>\n<p class=\"reader-text-block__paragraph\">Se trata de reconocer cu\u00e1les son tus talentos para ponerlos en valor, hasta el uso de t\u00e9cnicas avanzadas de marketing para comunicarlos eficazmente, fortaleciendo tus habilidades directivas para mejorar y promocionar tu carrera, negociar tu nivel salarial y posicionarte con seguridad dentro del mercado laboral.<\/p>\n<p class=\"reader-text-block__paragraph\">Adem\u00e1s, soy consciente de que detr\u00e1s de un gran l\u00edder hay un gran equipo, y por eso he decidido rodearme de personas expertas, cada una en su campo, unos m\u00e1s senior, otros m\u00e1s junior, para que el proyecto sea todav\u00eda m\u00e1s enriquecedor. En breve te presentar\u00e9 a todo el equipo multidisciplinar que tambi\u00e9n se viste la camiseta ENIT\u00a0para lograr que todas esas personas que han confiado en nosotros superen expectativas y nos consideren como una de las mejores inversiones que han hecho.<\/p>\n<div class=\"reader-image-block reader-image-block--full-width\">\n<figure class=\"reader-image-block__figure\">\n<div class=\"ivm-image-view-model   \">\n<div class=\"ivm-view-attr__img-wrapper ivm-view-attr__img-wrapper--use-img-tag display-flex\n\n    \"><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<p class=\"reader-text-block__paragraph\">Te invito a que nos conozcas mejor, <a href=\"https:\/\/www.diversia360.com\/enit\/formulario-de-registro\/\" target=\"_blank\" rel=\"noopener\">y a que te registres en nuestra comunidad,<\/a> para poder acceder a contenidos exclusivos que podr\u00e1n ayudarte en el desarrollo de tu carrera profesional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La semana pasada te hablaba sobre el emprendimiento, algo que, aunque no es camino f\u00e1cil, algunos \u201capasionados\u201d lo llevamos en nuestro ADN y luchamos por \u00e9l contra viento y marea. Hace unos d\u00edas, cenando con un grupo de amigos, uno de ellos me pregunt\u00f3 \u201cImma,...<\/p>\n","protected":false},"author":7,"featured_media":2910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[122,67],"tags":[48,150,151],"class_list":["post-6071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-pensamientos-propios","tag-directivos","tag-emprendimiento","tag-opentowork"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/posts\/6071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/comments?post=6071"}],"version-history":[{"count":0,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/posts\/6071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/media\/2910"}],"wp:attachment":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/media?parent=6071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/categories?post=6071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/tags?post=6071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}