{"id":4746,"date":"2022-06-25T12:01:41","date_gmt":"2022-06-25T10:01:41","guid":{"rendered":"https:\/\/www.diversia360.com\/enit\/?p=4746"},"modified":"2022-06-27T12:23:20","modified_gmt":"2022-06-27T10:23:20","slug":"se-puede-aprender-a-dirigir-y-desarrollar-mi-carrera-estudiando-10-minutos-al-dia","status":"publish","type":"post","link":"https:\/\/www.diversia360.com\/enit\/se-puede-aprender-a-dirigir-y-desarrollar-mi-carrera-estudiando-10-minutos-al-dia\/","title":{"rendered":"\u00bfSe puede aprender a dirigir y desarrollar mi carrera estudiando 10 minutos al d\u00eda?"},"content":{"rendered":"<p>Efectivamente si tu compromiso es el conocimiento, nosotros hemos creado el formato para que se adapte a tu vida, puedas aprender a tu ritmo, sin renunciar al acompa\u00f1amiento y aprendizaje grupal.<br \/>\nCompatibilizar tu momento de vida (trabajo, familia, actividades) con el aprendizaje diario sin horarios que te exijan asistir a una aula, o tengas que renunciar a tu tiempo libre.<br \/>\nEst\u00e1 totalmente testado!! Y Funciona!!  <\/p>\n<p>\u00a1Pero como en cualquier formaci\u00f3n en una escuela de negocios, lo que hacemos es explicar los contenidos de una manera mucho m\u00e1s efectiva:<br \/>\n\u27a1 El 35% de las clases son te\u00f3ricas con contenidos espec\u00edficos para que profundices en conceptos clave, y entiendas, de verdad tu punto de partida.<br \/>\n\u27a1 El 35% son ejercicios pr\u00e1cticos sobre tu candidatura y trayectoria, tus habilidades personales, logros y oportunidades profesionales, para que, reorganices la informaci\u00f3n, pongas foco en lo esencial y desarrolles las habilidades concretas que te ayudaran a dirigir tu carrera profesional y tomar las mejores decisiones para ti.<br \/>\n\u27a1 El \u00faltimo 35% conforma la s\u00edntesis en la presentaci\u00f3n de tu candidatura, tanto en tu CV como en RSS profesionales. Entrenar tu discurso y expresarlo de forma eficiente de acuerdo a tus objetivos, para que tengas m\u00e1s seguridad tanto en la superaci\u00f3n de entrevistas como en la negociaci\u00f3n de tu incorporaci\u00f3n al puesto deseas, evitando los errores que cometieron en el pasado. <\/p>\n<p>As\u00ed, con peque\u00f1as p\u00edldoras diarias te har\u00e1s con los contenidos que son realmente necesarios, profundizando lo justo en los conceptos y centr\u00e1ndonos en el uso de herramientas, metodolog\u00edas y la presentaci\u00f3n de casos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivamente si tu compromiso es el conocimiento, nosotros hemos creado el formato para que se adapte a tu vida, puedas aprender a tu ritmo, sin renunciar al acompa\u00f1amiento y aprendizaje grupal. Compatibilizar tu momento de vida (trabajo, familia, actividades) con el aprendizaje diario sin horarios...<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[127],"tags":[],"class_list":["post-4746","post","type-post","status-publish","format-standard","hentry","category-sobre-nuestra-metodologia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/posts\/4746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/comments?post=4746"}],"version-history":[{"count":0,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/posts\/4746\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/media?parent=4746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/categories?post=4746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.diversia360.com\/enit\/wp-json\/wp\/v2\/tags?post=4746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}